{"id":70710,"date":"2023-05-17T17:30:27","date_gmt":"2023-05-17T15:30:27","guid":{"rendered":"https:\/\/dezernat-zukunft.org\/?p=70710"},"modified":"2023-06-29T11:21:13","modified_gmt":"2023-06-29T09:21:13","slug":"importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz","status":"publish","type":"post","link":"https:\/\/dezernatzukunft.org\/en\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/","title":{"rendered":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz"},"content":{"rendered":"\n<p class=\"has-normal-font-size\"><strong><a href=\"mailto:felix.heilmann.ext@dezernatzukunft.org\" target=\"_blank\" rel=\"noreferrer noopener\">Felix Heilmann<\/a><\/strong>, Janek Steitz<\/p>\n\n\n<div class=\"executivesumgb41\" style=\"border-left: 8px solid #ee6174; text-align: left;\">\n<p>In den letzten Monaten haben wir uns gemeinsam mit Agora Energiewende und im Austausch mit Expert:innen aus dem gesamten Spektrum der Debatte mit der Frage besch\u00e4ftigt, inwiefern die aktuell diskutierten Ma\u00dfnahmen zum Ausbau der Versorgung mit Fl\u00fcssigerdgas (LNG) das Erreichen der Klimaziele gef\u00e4hrden k\u00f6nnen und welche Pfade es gibt, um sowohl die notwendige Gasversorgung sicherzustellen als auch die Klimaziele zu erreichen.<\/p>\n<p>Unser neues und heute ver\u00f6ffentlichtes Hintergrundpapier fasst die wichtigsten Erkenntnisse in drei Abschnitten zusammen: LNG-Produktion, Vertr\u00e4ge und Nachfrage\/Importe. Wir stellen fest, dass die Entwicklung neuer LNG-Exportterminals das gr\u00f6\u00dfte Risiko f\u00fcr die Verfehlung der Klimaziele birgt \u2013 und zudem weder die akuten Knappheiten in den globalen Gasm\u00e4rkten adressieren kann, noch finanziell sinnvoll ist. Im Gegensatz dazu k\u00f6nnen europ\u00e4ische Importterminals als Reservekapazit\u00e4ten f\u00fcr Krisenzeiten dienen. Voraussetzung daf\u00fcr ist aber, dass ihre Nutzung in Nicht-Krisenzeiten effektiv eingeschr\u00e4nkt wird.<\/p>\n<\/div>\n<h4><strong>Warum haben wir das Papier geschrieben?<\/strong><\/h4>\n<p>Der russische Angriff auf die Ukraine hat die Sicherung der Gasversorgung Deutschlands und Europas zu einem zentralen politischen und wirtschaftlichen Thema gemacht. Im Herbst 2022 haben wir uns erstmals ausf\u00fchrlich mit dem Thema besch\u00e4ftigt und <a href=\"https:\/\/dezernatzukunft.org\/wie-weiter-mit-dem-gas\/\" target=\"_blank\" rel=\"noopener\">in einem Geldbrief gefragt: Wie kann es gelingen, stabile Erdgaslieferungen zu sichern?<\/a> Braucht es langfristige Vertr\u00e4ge f\u00fcr Fl\u00fcssigerdgas (LNG)-Lieferungen, auch wenn sie auf den ersten Blick den Klimazielen zuwiderlaufen?<\/p>\n<p>Wir haben damals viele R\u00fcckmeldungen zu unserem Geldbrief bekommen und er war Grundlage f\u00fcr zahlreiche weitere Diskussionen. Es wurde deutlich, dass wir ein schwieriges Thema aufgegriffen hatten, das weiterer Auseinandersetzung bedurfte. Auch gesamtgesellschaftlich ist die Diskussion um Gasversorgung und LNG-Infrastruktur nach wie vor kontrovers, gleichzeitig wirkt die Debatte oft polarisiert, es gibt wenig Graut\u00f6ne oder inhaltliche Br\u00fccken zwischen den verschiedenen Lagern.<\/p>\n<p>Daher haben wir uns entschieden, dem Thema noch tiefer auf den Grund zu gehen \u2013 schlie\u00dflich stehen mit der Energiesicherheit und der Erreichung der Klimaziele zwei f\u00fcr die Zukunft Deutschlands und Europas absolut entscheidende Themen auf dem Spiel.<\/p>\n<p>Um herauszufinden, wo genau die Debatte steht und ob es weniger diskutierte Argumente, Fakten und Ideen gibt, die die verschiedenen Akteure zusammenbringen k\u00f6nnten, haben wir daf\u00fcr im Februar Stakeholder aus dem gesamten Spektrum der Debatte zu einem virtuellen Workshop nach Chatham House Regeln eingeladen. Gemeinsam haben wir diskutiert: Welche LNG-Entscheidungen f\u00fchren zu den gr\u00f6\u00dften Klimarisiken und warum? Wie k\u00f6nnen LNG-Strategien aussehen, die die gleicherma\u00dfen wichtigen Ziele Energiesicherheit und Klimaschutz erreichen?<\/p>\n<p>Mit Vertreter:innen aus Industrie, Zivilgesellschaft, internationalen Organisationen und Forschungsinstituten haben wir diese Fragen offen und konstruktiv beleuchtet. Aus dem Austausch ergaben sich viele neue Perspektiven und Nuancen, die wir in den folgenden Wochen in bilateralen Gespr\u00e4chen weiter vertiefen konnten.<\/p>\n<p>Am Ende stand eine ganze Reihe von Erkenntnissen, die in der aktuellen LNG-Debatte wenig Beachtung finden, aber f\u00fcr das Erreichen von Energiesicherheit und Klimaschutz von gro\u00dfer Bedeutung sein k\u00f6nnen. Gemeinsam mit Agora Energiewende haben wir uns daher entschlossen, diese Erkenntnisse in Form von zehn Thesen aufzuschreiben und zu ver\u00f6ffentlichen, um so eine Grundlage f\u00fcr neue Nuancen und Differenzierungen in der LNG-Debatte zu schaffen. Diese zehn Thesen finden sich in unserem heute ver\u00f6ffentlichten <a href=\"https:\/\/dezernatzukunft.org\/en\/lng-climate-and-energy-security-towards-a-comprehensive-approach-for-europe\/\" target=\"_blank\" rel=\"noopener\">Hintergrundpapier<\/a><a href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<!--<sup--><\/sup><\/a>, die zentralen Implikationen, auch f\u00fcr den morgen beginnenden G7-Gipfel in Hiroshima, haben wir in einem Meinungsbeitrag f\u00fcr <a href=\"https:\/\/www.zeit.de\/wirtschaft\/2023-05\/gasversorgung-energiewende-klimaziele-fluessiggas\" target=\"_blank\" rel=\"noopener\">ZEIT Online<\/a> zusammengefasst.<\/p>\n<h4><strong>Was haben wir gelernt?<\/strong><\/h4>\n<p>Das vielleicht wichtigste Ergebnis unserer Arbeit: w\u00e4hrend in Deutschland vor allem \u00fcber <em>Import\u00ad<\/em>-Terminals gesprochen wird, birgt der Bau von <em>Export<\/em>-Terminals f\u00fcr LNG, etwa in den USA oder Katar, das mit Abstand gr\u00f6\u00dfte Risiko, zus\u00e4tzliche Emissionen zu zementieren. Denn: Exportterminals sind das mit Abstand teuerste Element in der LNG-Lieferkette. Einmal gebaut, haben die Betreiber ein starkes Interesse daran, sie zu nutzen. So entsteht ein h\u00f6heres LNG-Angebot, welches die Preise sinken und die Nachfrage steigen l\u00e4sst. Das Ergebnis ist ein global h\u00f6herer Gasverbrauch und zus\u00e4tzliche Emissionen.<\/p>\n<p><strong>Abbildung 1<\/strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-70646  aligncenter\" src=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1.png\" alt=\"\" width=\"749\" height=\"338\" srcset=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1.png 1600w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-300x135.png 300w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-1024x461.png 1024w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-768x346.png 768w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-1536x692.png 1536w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-100x45.png 100w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-1-1184x534.png 1184w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><\/p>\n<p>In Deutschland stehen dagegen vor allem die Terminals zum <em>Import<\/em> von LNG im Zentrum der Debatte. Die <a href=\"https:\/\/www.ndr.de\/nachrichten\/mecklenburg-vorpommern\/Klimaaktivisten-um-Luisa-Neubauer-Protest-auf-Ruegen-gegen-LNG,lng760.html\" target=\"_blank\" rel=\"noopener\">Klimabewegung und Anwohner<\/a>, beispielsweise auf R\u00fcgen, f\u00fcrchten, dass die Pl\u00e4ne der Bundesregierung hierf\u00fcr <a href=\"https:\/\/newclimate.org\/sites\/default\/files\/2023-02\/LNG%20Deutschland%20Annex.pdf\" target=\"_blank\" rel=\"noopener\">zu h\u00f6heren Emissionen f\u00fchren und mit den Klimazielen unvereinbar seien<\/a>. Die Ampel-Koalition hingegen sieht keinen Widerspruch mit den Klimazielen und argumentiert, dass die Terminals <a href=\"https:\/\/www.tagesspiegel.de\/politik\/habeck-raumt-lng-uberkapazitaten-ein-konnen-nicht-davon-ausgehen-dass-immer-alles-gut-geht-9753788.html\" target=\"_blank\" rel=\"noopener\">zur Sicherung der Gasversorgung unverzichtbar seien<\/a>, gerade auch als Versicherung gegen einen unerwarteten Ausfall von, zum Beispiel, norwegischen Gaslieferungen.<\/p>\n<p>Und tats\u00e4chlich: ein Terminal, das in normalen Zeiten ungenutzt bliebe und nur als Reserve f\u00fcr m\u00f6gliche Notf\u00e4lle vorgehalten w\u00fcrde, hat in der Tat keine direkten Auswirkungen auf Gasverbrauch und somit Emissionen. Als Reserve sind LNG-Terminals zwar ohne Weiteres nicht wirtschaftlich. Die ungedeckten Kosten k\u00f6nnten und sollten als sicherheitspolitische Ausgabe vom Bund getragen werden.<\/p>\n<p>Problematisch im Hinblick aufs Klima ist jedoch, dass die Vorhaltung der Kapazit\u00e4ten als Reserve bislang kaum regulatorisch verankert ist. Gem\u00e4\u00df der aktuellen <a href=\"https:\/\/www.gesetze-im-internet.de\/lngv\/BJNR632100022.html\" target=\"_blank\" rel=\"noopener\">LNG-Verordnung<\/a> d\u00fcrfen Terminalbetreiber in Deutschland 90 Prozent ihrer Importkapazit\u00e4ten langfristig vermarkten, und hiervon 80 Prozent f\u00fcr mehr als 15 Jahre. Das hei\u00dft: es steht Terminalbetreibern und Gasimporteuren frei, diese \u00fcber lange Zeitr\u00e4ume auch in Nicht-Krisenzeiten nahezu vollst\u00e4ndig auszulasten \u2013 und im Zweifel nicht in Deutschland ben\u00f6tigtes Gas global weiterzuverkaufen. Das steht im krassen Gegensatz zur <a href=\"https:\/\/www.bmwk.de\/Redaktion\/DE\/Downloads\/Energie\/20230303-lng-bericht.pdf?__blob=publicationFile&amp;v=6\" target=\"_blank\" rel=\"noopener\">Planung der Bundesregierung, dass zum Jahr 2030 \u00fcber 75 Prozent der geplanten Importkapazit\u00e4ten als Reserve dienen sollen<\/a>. Es muss politisch verbindlich sichergestellt werden, dass Terminals, die als Sicherheitsreserve dienen sollen, in normalen Zeiten nicht ausgelastet werden k\u00f6nnen.<\/p>\n<p><strong>Als Faustregel muss deshalb gelten: neue Importterminals mit Nutzungsbeschr\u00e4nkung ja, neue Exportprojekte nein.<\/strong> Aber wie ist damit die Versorgungssicherheit gew\u00e4hrleistet?<\/p>\n<p>Zun\u00e4chst die gute Nachricht: Auch ohne den Bau weiterer neuer Exportterminals, die heute noch keine finale Investitionszusage haben, <a href=\"https:\/\/ieefa.org\/resources\/global-lng-outlook-2023-27\" target=\"_blank\" rel=\"noopener\">wird sich die globale LNG-Versorgungssituation in den kommenden Jahren strukturell stark entspannen<\/a>. Vor allem in den USA und Katar befinden sich bereits jetzt viele Exportprojekte im Bau, insgesamt wird sich bis 2027 das globale LNG-Angebot auf dem Weltmarkt um rund ein Drittel erh\u00f6hen. Ab 2027 \u00fcberschreiten die verf\u00fcgbaren Exportkapazit\u00e4ten dann die klimakompatible LNG-Nachfrage um rund 20 Prozent. Das zeigen Analysen der <a href=\"https:\/\/www.igu.org\/resources\/world-lng-report-2022\/\" target=\"_blank\" rel=\"noopener\">Internationalen Gas Union<\/a> sowie des <a href=\"https:\/\/www.bp.com\/content\/dam\/bp\/business-sites\/en\/global\/corporate\/pdfs\/energy-economics\/energy-outlook\/bp-energy-outlook-2023.pdf\" target=\"_blank\" rel=\"noopener\">Energiekonzerns bp<\/a>. Auch eine Auswertung der <a href=\"https:\/\/www.iea.org\/reports\/world-energy-outlook-2022\" target=\"_blank\" rel=\"noopener\">Internationalen Energieagentur<\/a> mit Fokus auf den \u00fcberregionalen LNG-Handel best\u00e4tigt dieses Ergebnis.<\/p>\n<p><strong>Abbildung 2<\/strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-70648  aligncenter\" src=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2.png\" alt=\"\" width=\"751\" height=\"784\" srcset=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2.png 1600w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-287x300.png 287w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-981x1024.png 981w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-768x802.png 768w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-1472x1536.png 1472w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-100x104.png 100w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Abbildung-2-1184x1236.png 1184w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/p>\n<p>Selbst in einem Extremszenario, in dem die LNG-Nachfrage weiter ansteigt und die globalen Klimaziele gerissen werden, k\u00f6nnen die dann verf\u00fcgbaren Exportkapazit\u00e4ten bis mindestens in die 2030er Jahre ausreichen. Dabei ist noch nicht ber\u00fccksichtigt, dass Deutschland durch eine st\u00e4rkere Unterst\u00fctzung f\u00fcr den Ausbau der erneuerbaren Energien und von Energieeffizienz in Entwicklungs- und Schwellenl\u00e4ndern die LNG-Nachfrage senken kann. Durch diesen Verbrauchsr\u00fcckgang st\u00fcnde dem Weltmarkt mehr LNG zur Verf\u00fcgung.<\/p>\n<p>Dieses Prinzip wurde bereits erfolgreich gemeinsam mit \u00c4gypten umgesetzt und lie\u00dfe sich \u2013 auch mit geopolitischen Vorteilen \u2013 auf andere L\u00e4nder \u00fcbertragen. <a href=\"https:\/\/www.climatechangenews.com\/2022\/11\/11\/german-us-cash-aims-to-cut-egypts-gas-use-and-boost-exports\/\" target=\"_blank\" rel=\"noopener\">Mit Unterst\u00fctzung aus Deutschland und den USA beschleunigt \u00c4gypten seine Pl\u00e4ne zum Ausbau der Erneuerbaren und legt zw\u00f6lf alte Gaskraftwerke vorzeitig still<\/a>, was den LNG-Bedarf um zwei Milliarden Kubikmeter reduzieren wird. Neue LNG-Export-Terminals zu bauen ist also nicht nur teuer und unvereinbar mit den globalen Klimazielen, es ist aller Wahrscheinlichkeit nach nicht notwendig.<\/p>\n<p>Das letzte Jahr hat au\u00dferdem gezeigt, dass <a href=\"https:\/\/www.spglobal.com\/commodityinsights\/en\/market-insights\/blogs\/lng\/102622-europe-lng-russian-gas-ukraine-war\" target=\"_blank\" rel=\"noopener\">europ\u00e4ische Importeure notfalls gro\u00dfe LNG-Mengen \u00fcber den Spotmarkt beziehen k\u00f6nnen<\/a>. Dies ist aber teuer und kann mit sp\u00fcrbaren Unsicherheiten und Preisschwankungen einhergehen. W\u00fcnschenswert ist ein solches Szenario also nicht \u2013 aber es funktioniert, um im \u00e4u\u00dfersten Notfall W\u00e4rme und Strom zu sichern.<\/p>\n<p>\u00dcber kluge Regulierung kann die Bundesregierung die wirtschaftlichen Risiken merklich reduzieren: Durch eine Anpassung der LNG-Verordnung lie\u00dfe sich f\u00fcr einen deutlich gr\u00f6\u00dferen Anteil der Importkapazit\u00e4ten regulatorisch festlegen, dass diese nur mit Kurz- und Mittelfristvertr\u00e4gen durch private Akteure abrufbar sind. Dies verhindert, dass neue Exportkapazit\u00e4ten angereizt werden. Denn neue Exportterminals erfordern in der Regel aufgrund ihrer hohen Kapitalkosten Langfristvertr\u00e4ge f\u00fcr eine erfolgreiche Finanzierung. Daher bieten mittelfristige Vertr\u00e4ge von maximal 10 Jahren Laufzeit eine gute Kombination aus Verl\u00e4sslichkeit und Planbarkeit, ohne langfristige Abh\u00e4ngigkeiten zu schaffen, die Klimapfaden widersprechen.<\/p>\n<p>Dies w\u00e4re gegebenenfalls mit zus\u00e4tzlichen Kosten verbunden. <a href=\"https:\/\/www.reuters.com\/article\/lng-trade-contracts-idUSKBN2OI1H8\" target=\"_blank\" rel=\"noopener\">Gasexporteure und Energiefirmen wie Shell oder bp bieten bisher bevorzugt langfristige Liefervertr\u00e4ge an<\/a>, um das Risiko eines Gasnachfrager\u00fcckgangs gem\u00e4\u00df globaler Klimaziele auf die Importeure zu \u00fcbertragen. Mittelfristige Vertr\u00e4ge sind daher heute selten und teurer, eine \u00f6ffentliche Bezuschussung privater Akteure k\u00f6nnte anf\u00e4nglich erforderlich sein. So oder so: Der Abschluss von Mittelfristvertr\u00e4gen, notfalls staatlich bef\u00f6rdert, ist dem Abschluss von Langfristvertr\u00e4gen, die neue Exportprojekte erm\u00f6glichen, aus Klimasicht vorzuziehen.<\/p>\n<p>Deutschland und Europa k\u00f6nnen also durchaus Sicherheitsreserven f\u00fcr LNG-Importe entwickeln und generell ihre heimische Nachfrage w\u00e4hrend des \u00dcbergangs zur Klimaneutralit\u00e4t absichern, ohne neue fossile Pfadabh\u00e4ngigkeiten zu schaffen. Daf\u00fcr ist es aber entscheidend, dass keine zus\u00e4tzlichen Exportprojekte erm\u00f6glicht werden. Dar\u00fcber hinaus k\u00f6nnen nur der schnellstm\u00f6gliche Ausbau erneuerbarer Energien und weitere Effizienzgewinne die fossile Abh\u00e4ngigkeit strukturell beenden. Das sollte auch die Linie der Bundesregierung auf dem am Freitag startenden G7-Gipfel in Hiroshima sein.<\/p>\n<p><strong>Unsere Leseempfehlungen:<\/strong> \u00a0Thematisch passend zum Geldbrief k\u00f6nnen wir euch die <a href=\"https:\/\/www.agora-energiewende.de\/en\/publications\/breaking-free-from-fossil-gas-1\/\" target=\"_blank\" rel=\"noopener\">Studie<\/a> von Agora Energiewende an Herz legen, welche einen Weg skizziert, wie wir ein klimaneutrales Europa erreichen k\u00f6nnen.<\/p>\n<p>Passend zu unserer fiskalpolitischen Arbeit wurde gestern ein <a href=\"https:\/\/www.imf.org\/en\/News\/Articles\/2023\/05\/16\/mcs051623-germany-staff-concluding-statement-of-the-2023-article-iv-mission\" target=\"_blank\" rel=\"noopener\">IMF Bericht<\/a> ver\u00f6ffentlicht, der sich kritisch mit der deutschen Schuldenbremsenregelung auseinandersetzt.<\/p>\n<hr \/>\n<h4>Fu\u00dfnoten<\/h4>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Das Papier ist auf Englisch. Eine deutsche \u00dcbersetzung wird in n\u00e4chster Zeit folgen.<\/p>\n<hr \/>\n<h4><strong>Medien- und Veranstaltungsbericht 17.05.2023<\/strong><\/h4>\n<p>Event der letzten Wochen: Janek war beim Forum for a New Economy zu Gast und diskutierte zusammen mit Prof. Micheal H\u00fcther vom IW K\u00f6ln, ob Deutschland den Energiepreisschock \u00fcberleben wird. Eine Aufzeichnung findet ihr <a href=\"https:\/\/www.youtube.com\/watch?v=_Ht6j8T8n0M\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-70700 aligncenter\" src=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-scaled.jpg\" alt=\"\" width=\"750\" height=\"465\" srcset=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-scaled.jpg 2560w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-300x186.jpg 300w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-1024x635.jpg 1024w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-768x476.jpg 768w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-1536x953.jpg 1536w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-2048x1271.jpg 2048w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-100x62.jpg 100w, https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Foto-Janek-F4NE-1184x735.jpg 1184w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<ul>\n<li><strong>Medienerw\u00e4hnungen und Auftritte<\/strong>\n<ul>\n<li>Am 08.05.2023 war Janek beim XII. New Paradigm Workshop &#8211; Resetting the Economy after the Crises zu Gast. Er diskutierte dort im Speed-Dating-Format zu \u201cWird Deutschlands Industrie den Energieschock \u00fcberleben? Empirische Ergebnisse und Projektionen f\u00fcr einzelne Wirtschaftssektoren\u201d. Ihr k\u00f6nnt euch die Aufzeichnung <a href=\"https:\/\/www.youtube.com\/watch?v=_Ht6j8T8n0M\" target=\"_blank\" rel=\"noopener\">hier<\/a> ansehen.<\/li>\n<li>Am 09.05.23 wurde Max Krah\u00e9 im <a href=\"https:\/\/www.aftonbladet.se\/kultur\/a\/BWqGE7\/eric-rosen-om-katalys-10-ar\" target=\"_blank\" rel=\"noopener\">Aftonbladet<\/a> erw\u00e4hnt.<\/li>\n<li>Am 15.05.23 hat das Magazin\u00a0<a href=\"https:\/\/www.politik-kommunikation.de\/magazin\/n-143-thema-15-young-thinkers\/\" target=\"_blank\" rel=\"noopener\">politik&amp;kommunikation<\/a> angek\u00fcndigt, Philippa als eine von 15 Young Thinkers im Themenbereich &#8220;Finanzpolitik&#8221; auszuzeichnen. Die Auszeichnung wird am 22.05 im Rahmen der Politikawards 2023 in Berlin vergeben.<\/li>\n<li>Heute am 17.05.23 war Philippa bei <a href=\"https:\/\/www.youtube.com\/watch?v=GK9X0HaIRXI\" target=\"_blank\" rel=\"noopener\">The Beyond Growth 2023 Conference<\/a> zu Gast und hat einen Input gegeben. Die Veranstaltung kann <a href=\"https:\/\/www.youtube.com\/watch?v=GK9X0HaIRXI\" target=\"_blank\" rel=\"noopener\">hier<\/a> nachgeschaut werden.<\/li>\n<li>Ebenfalls heute am 17.05.23 ist der Gastbeitrag \u201eSo kann Deutschland Gas kaufen und trotzdem die Klimaziele schaffen\u201c von Felix, Janek und Simon M\u00fcller (Agora Energiewende) bei der <a href=\"https:\/\/www.zeit.de\/wirtschaft\/2023-05\/gasversorgung-energiewende-klimaziele-fluessiggas\" target=\"_blank\" rel=\"noopener\">Zeit<\/a> erschienen.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Veranstaltungen<\/strong>\n<ul>\n<li>Am 20.05.23 ist Max Krah\u00e9 bei der <a href=\"https:\/\/www.spd-hamburg.de\/termine\/\" target=\"_blank\" rel=\"noopener\">SPD Eimsb\u00fcttel<\/a> zum Thema \u201eFinanzmythen brechen, Zukunft gestalten\u201c zu Gast. Mit auf dem Podium sind Maurice H\u00f6fgen (\u00d6konom &amp; Buchautor) und Martyna Linartas (Politologin &amp; Aktivistin).<\/li>\n<li>Am 25.05.23 um 16:30 Uhr wird Max Krah\u00e9 in einem Webinar sein neustes Papier \u00fcber die <a href=\"https:\/\/dezernatzukunft.org\/italiens-stagnation-verstehen\/\" target=\"_blank\" rel=\"noopener\">Stagnation Italiens<\/a> Zur Anmeldung und weiteren Infos geht es <a href=\"https:\/\/dezernatzukunft.org\/events\/open-house-webinar-mit-max-krahe\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/li>\n<li>Am 25.05.23 ist Janek zu Gast in Paris bei der FES und spricht auf einer Podiumsdiskussion zum Thema \u201eWhat European strategy to achieve a net zero emissions industry?\u201c.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p class=\"executivesum\" style=\"border-left: 8px solid #ee6174; text-align: center;\"><em>The\u00a0<b data-stringify-type=\"bold\">Geldbrief<\/b> is our newsletter on current developments in economic, fiscal, and monetary policy. We appreciate your feedback and suggestions. Send it to felix.heilmann.ext<\/em><em>[at]dezernatzukunft.org<\/em><\/p>\n<hr \/>","protected":false},"excerpt":{"rendered":"<p>In den letzten Monaten haben wir haben uns gemeinsam mit Agora Energiewende und im Austausch mit Expert:innen aus dem gesamten Spektrum der Debatte mit der Frage besch\u00e4ftigt, inwiefern die aktuell diskutierten Ma\u00dfnahmen zum Ausbau der Versorgung mit Fl\u00fcssigerdgas (LNG) das Erreichen der Klimaziele gef\u00e4hrden k\u00f6nnen und welche Pfade es gibt, um sowohl die notwendige Gasversorgung sicherzustellen als auch die Klimaziele zu erreichen.<\/p>\n","protected":false},"author":66,"featured_media":70638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[161],"tags":[288,289,227,174,286,287,265,266],"class_list":["post-70710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geldbrief-en","tag-climate-en","tag-economic-policy-en","tag-europa-en","tag-europe","tag-fh-en","tag-js-en","tag-klima-en","tag-wirtschaftspolitik-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft<\/title>\n<meta name=\"description\" content=\"Institut f\u00fcr Makrofinanzen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft\" \/>\n<meta property=\"og:description\" content=\"Institut f\u00fcr Makrofinanzen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Dezernat Zukunft\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T15:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-29T09:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felix Heilmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DezernatZ\" \/>\n<meta name=\"twitter:site\" content=\"@DezernatZ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felix Heilmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\"},\"author\":{\"name\":\"Felix Heilmann\",\"@id\":\"https:\/\/dezernatzukunft.org\/#\/schema\/person\/d93fc1e702760ef2dac01c880e0b2a8b\"},\"headline\":\"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz\",\"datePublished\":\"2023-05-17T15:30:27+00:00\",\"dateModified\":\"2023-06-29T09:21:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\"},\"wordCount\":1876,\"publisher\":{\"@id\":\"https:\/\/dezernatzukunft.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png\",\"keywords\":[\"Climate\",\"Economic policy\",\"Europa\",\"Europe\",\"FH\",\"JS\",\"Klima\",\"Wirtschaftspolitik\"],\"articleSection\":[\"Geldbrief\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\",\"url\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\",\"name\":\"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft\",\"isPartOf\":{\"@id\":\"https:\/\/dezernatzukunft.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png\",\"datePublished\":\"2023-05-17T15:30:27+00:00\",\"dateModified\":\"2023-06-29T09:21:13+00:00\",\"description\":\"Institut f\u00fcr Makrofinanzen\",\"breadcrumb\":{\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage\",\"url\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png\",\"contentUrl\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png\",\"width\":1600,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dezernatzukunft.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dezernatzukunft.org\/#website\",\"url\":\"https:\/\/dezernatzukunft.org\/\",\"name\":\"Dezernat Zukunft\",\"description\":\"Institut f\u00fcr Makrofinanzen\",\"publisher\":{\"@id\":\"https:\/\/dezernatzukunft.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dezernatzukunft.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dezernatzukunft.org\/#organization\",\"name\":\"Dezernat Zukunft\",\"url\":\"https:\/\/dezernatzukunft.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dezernatzukunft.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2022\/05\/Dezernat_Zukunft-01_Zeichenfla\u0308che-1.png\",\"contentUrl\":\"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2022\/05\/Dezernat_Zukunft-01_Zeichenfla\u0308che-1.png\",\"width\":966,\"height\":167,\"caption\":\"Dezernat Zukunft\"},\"image\":{\"@id\":\"https:\/\/dezernatzukunft.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/DezernatZ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dezernatzukunft.org\/#\/schema\/person\/d93fc1e702760ef2dac01c880e0b2a8b\",\"name\":\"Felix Heilmann\",\"url\":\"https:\/\/dezernatzukunft.org\/en\/author\/fheilmann\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft","description":"Institut f\u00fcr Makrofinanzen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/","og_locale":"en_US","og_type":"article","og_title":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft","og_description":"Institut f\u00fcr Makrofinanzen","og_url":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/","og_site_name":"Dezernat Zukunft","article_published_time":"2023-05-17T15:30:27+00:00","article_modified_time":"2023-06-29T09:21:13+00:00","og_image":[{"width":1600,"height":933,"url":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png","type":"image\/png"}],"author":"Felix Heilmann","twitter_card":"summary_large_image","twitter_creator":"@DezernatZ","twitter_site":"@DezernatZ","twitter_misc":{"Written by":"Felix Heilmann","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#article","isPartOf":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/"},"author":{"name":"Felix Heilmann","@id":"https:\/\/dezernatzukunft.org\/#\/schema\/person\/d93fc1e702760ef2dac01c880e0b2a8b"},"headline":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz","datePublished":"2023-05-17T15:30:27+00:00","dateModified":"2023-06-29T09:21:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/"},"wordCount":1876,"publisher":{"@id":"https:\/\/dezernatzukunft.org\/#organization"},"image":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage"},"thumbnailUrl":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png","keywords":["Climate","Economic policy","Europa","Europe","FH","JS","Klima","Wirtschaftspolitik"],"articleSection":["Geldbrief"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/","url":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/","name":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz - Dezernat Zukunft","isPartOf":{"@id":"https:\/\/dezernatzukunft.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage"},"image":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage"},"thumbnailUrl":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png","datePublished":"2023-05-17T15:30:27+00:00","dateModified":"2023-06-29T09:21:13+00:00","description":"Institut f\u00fcr Makrofinanzen","breadcrumb":{"@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#primaryimage","url":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png","contentUrl":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2023\/05\/Beitragsbild_Geldbrief-41.png","width":1600,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/dezernatzukunft.org\/importreserve-statt-exportflut-lng-zwischen-energiesicherheit-und-klimaschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dezernatzukunft.org\/en\/"},{"@type":"ListItem","position":2,"name":"Importreserve statt Exportflut: LNG zwischen Energiesicherheit und Klimaschutz"}]},{"@type":"WebSite","@id":"https:\/\/dezernatzukunft.org\/#website","url":"https:\/\/dezernatzukunft.org\/","name":"Dezernat Zukunft","description":"Institut f\u00fcr Makrofinanzen","publisher":{"@id":"https:\/\/dezernatzukunft.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dezernatzukunft.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dezernatzukunft.org\/#organization","name":"Dezernat Zukunft","url":"https:\/\/dezernatzukunft.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dezernatzukunft.org\/#\/schema\/logo\/image\/","url":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2022\/05\/Dezernat_Zukunft-01_Zeichenfla\u0308che-1.png","contentUrl":"https:\/\/dezernatzukunft.org\/wp-content\/uploads\/2022\/05\/Dezernat_Zukunft-01_Zeichenfla\u0308che-1.png","width":966,"height":167,"caption":"Dezernat Zukunft"},"image":{"@id":"https:\/\/dezernatzukunft.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DezernatZ"]},{"@type":"Person","@id":"https:\/\/dezernatzukunft.org\/#\/schema\/person\/d93fc1e702760ef2dac01c880e0b2a8b","name":"Felix Heilmann","url":"https:\/\/dezernatzukunft.org\/en\/author\/fheilmann\/"}]}},"_links":{"self":[{"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/posts\/70710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/comments?post=70710"}],"version-history":[{"count":3,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/posts\/70710\/revisions"}],"predecessor-version":[{"id":70715,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/posts\/70710\/revisions\/70715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/media\/70638"}],"wp:attachment":[{"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/media?parent=70710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/categories?post=70710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dezernatzukunft.org\/en\/wp-json\/wp\/v2\/tags?post=70710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}